{"id":3920,"date":"2026-09-01T16:02:35","date_gmt":"2026-09-01T10:32:35","guid":{"rendered":"https:\/\/ambcolombo.esteri.it\/?p=3920"},"modified":"2026-09-01T16:02:35","modified_gmt":"2026-09-01T10:32:35","slug":"premi-2026-per-la-ricerca-linnovazione-e-la-cooperazione-scientifica","status":"publish","type":"post","link":"https:\/\/ambcolombo.esteri.it\/it\/news\/dall_ambasciata\/2026\/09\/premi-2026-per-la-ricerca-linnovazione-e-la-cooperazione-scientifica\/","title":{"rendered":"Premi 2026 per la ricerca, l&#8217;innovazione e la cooperazione scientifica"},"content":{"rendered":"<p>La Sede \u00e8 lieta di segnalare tre opportunit\u00e0 promosse nell\u2019ambito della valorizzazione della ricerca, dell\u2019innovazione e della cooperazione scientifica internazionale, rivolte a ricercatori italiani attivi all\u2019estero, innovatori e scienziate straniere impegnate nella cooperazione scientifica bilaterale.<\/p>\n<p>Il termine per la presentazione delle candidature per tutti e tre i premi \u00e8 fissato al <strong><u>18 settembre 2026<\/u><\/strong>. Le candidature devono essere inviate al seguente indirizzo email: <a href=\"mailto:ambcolombo.concorsi@esteri.it\"><strong>ambcolombo.concorsi@esteri.it<\/strong><\/a>.<\/p>\n<ol>\n<li><strong><u>PREMIO FARNESINA &#8211; ITALIAN BILATERAL SCIENTIFIC COOPERATION AWARD<\/u><\/strong><\/li>\n<\/ol>\n<p>Il <strong>\u201cPremio Farnesina \u2013 Italian Bilateral Scientific Cooperation Award\u201d<\/strong> \u00e8 rivolto a giovani ricercatori italiani attivi all\u2019estero e mira a promuovere la mobilit\u00e0 scientifica verso l\u2019Italia e a favorire il rientro e la valorizzazione dei talenti italiani.<\/p>\n<p>Il vincitore avr\u00e0 l\u2019opportunit\u00e0 di svolgere un <strong>periodo di ricerca di tre mesi in Italia<\/strong> presso un Ente di ricerca selezionato dal <strong>CoPER \u2013 Consulta dei Presidenti degli Enti di Ricerca<\/strong>, coerente con il proprio ambito di ricerca. Il Premio prevede inoltre un contributo di circa <strong>15.000 euro<\/strong> per le spese connesse al soggiorno durante il periodo di ricerca.<\/p>\n<p><strong>Principali requisiti: <\/strong><\/p>\n<ul>\n<li>et\u00e0 non superiore a <strong>35 anni<\/strong> al momento della data di pubblicazione dell\u2019avviso;<\/li>\n<li>residenza nel Paese di candidatura (Sri Lanka) almeno dal <strong>1\u00b0 gennaio 2021<\/strong>;<\/li>\n<li>esperienza compresa tra <strong>3 e 7 anni dal conseguimento del dottorato di ricerca (PhD)<\/strong>;<\/li>\n<li>comprovata attivit\u00e0 scientifica di alto livello e collaborazioni di ricerca internazionali.<\/li>\n<\/ul>\n<p>Per maggiori informazioni sulle finalit\u00e0 del Premio, criteri di valutazione, procedura di selezione e sulle modalit\u00e0 di candidatura, si invita a consultare il <a href=\"https:\/\/ambcolombo.esteri.it\/wp-content\/uploads\/2026\/08\/Premio-Farnesina-Italian-Bilateral-Scientific-Cooperation-Award.pdf.\">bando completo<\/a>.<\/p>\n<p>Il <strong>Nomination Form<\/strong> \u00e8 disponibile al seguente link <a href=\"https:\/\/ambcolombo.esteri.it\/wp-content\/uploads\/2026\/08\/Premio-Farnesina-Nomination-Form.pdf\">Premio Farnesina &#8211; Nomination Form<\/a>.<\/p>\n<ol start=\"2\">\n<li><strong><u>PREMIO &#8220;L&#8217;INNOVAZIONE CHE PARLA ITALIANO&#8221;<\/u><\/strong><\/li>\n<\/ol>\n<p>Il Premio <strong>\u201cL\u2019innovazione che parla italiano\u201d<\/strong> riconosce l\u2019alto valore innovativo di <strong>startup tecnologiche fondate all\u2019estero da cittadini italiani<\/strong>.<\/p>\n<p>Il vincitore sar\u00e0 invitato a presentare la propria attivit\u00e0 di ricerca e innovazione in occasione della <strong>Conferenza degli Addetti scientifici, spaziali e degli Esperti agricoli<\/strong>, in programma a Reggio Calabria nel mese di novembre, e ricever\u00e0 un diploma e una targa celebrativa.<\/p>\n<p><strong>Principali requisiti: <\/strong><\/p>\n<ul>\n<li>cittadinanza italiana;<\/li>\n<li>possesso di un titolo di studio universitario e svolgimento di almeno parte del percorso di studi universitari o post-universitari in Italia;<\/li>\n<li>essere fondatore o co-fondatore di una <strong>startup innovativa a significativa caratterizzazione tecnologica<\/strong>, costituita da non pi\u00f9 di cinque anni e operativa in Sri Lanka.<\/li>\n<\/ul>\n<p>Per maggiori informazioni sulle modalit\u00e0 di presentazione delle candidature e sui criteri di valutazione, si invita a consultare il <a href=\"https:\/\/ambcolombo.esteri.it\/wp-content\/uploads\/2026\/08\/Premio-Linnovazione-che-parla-italiano.pdf\">bando completo<\/a>.<\/p>\n<p>Il <strong>Modulo di candidatura<\/strong> \u00e8 disponibile al seguente link <a href=\"https:\/\/ambcolombo.esteri.it\/wp-content\/uploads\/2026\/08\/PremioLinnovazione-che-parla-italiano-Modulo-candidatura.pdf\">Premio L&#8217;innovazione che parla italiano &#8211; Modulo Candidatura<\/a>.<\/p>\n<ol start=\"3\">\n<li><strong><u>PREMIO &#8220;SCIENCE, SHE SAYS!&#8221;<\/u><\/strong><\/li>\n<\/ol>\n<p>Il Premio <strong>\u201cScience, She Says!\u201d<\/strong> \u00e8 rivolto a <strong>giovani ricercatrici straniere under 40<\/strong> che si siano distinte per il loro contributo allo sviluppo della cooperazione scientifica bilaterale.<\/p>\n<p>Saranno premiate cinque ricercatrici provenienti rispettivamente da <strong>Africa e Medio Oriente, Asia e Pacifico, Europa, America centrale e meridionale e Caraibi, Nord America<\/strong>. Il riconoscimento, consistente in un diploma e una targa celebrativa, sar\u00e0 conferito in occasione della <strong>Giornata della ricerca italiana nel mondo<\/strong>.<\/p>\n<p><strong>Principali requisiti<\/strong><\/p>\n<ul>\n<li>et\u00e0 non superiore a <strong>40 anni al 15 settembre 2026<\/strong>;<\/li>\n<li>residenza nel Paese di candidatura (Sri Lanka) almeno dal <strong>1\u00b0 gennaio 2024<\/strong>;<\/li>\n<li>eccellente percorso accademico e\/o scientifico e comprovati risultati nell&#8217;attivit\u00e0 di ricerca;<\/li>\n<li>significativo contributo alla <strong>cooperazione scientifica bilaterale<\/strong> in qualsiasi settore della scienza e della tecnologia.<\/li>\n<\/ul>\n<p>La candidatura deve essere presentata da una personalit\u00e0 scientifica qualificata appartenente a un\u2019Universit\u00e0, Accademia scientifica, Istituto di ricerca o altra istituzione scientifica competente. <strong>Non sono ammesse autocandidature n\u00e9 candidature di gruppi.<\/strong><\/p>\n<p>Per maggiori informazioni sui criteri di valutazione, sulla procedura di selezione e sulle modalit\u00e0 di candidatura, si invita a consultare il <a href=\"https:\/\/ambcolombo.esteri.it\/wp-content\/uploads\/2026\/08\/Premio-Science-She-Says.pdf\">bando completo.<\/a><\/p>\n<p>Il <strong>Nomination Form<\/strong> \u00e8 disponibile al seguente link <a href=\"https:\/\/ambcolombo.esteri.it\/wp-content\/uploads\/2026\/08\/Premio-Science-She-Says-Nomination-Form.pdf\">Premio Science She Says &#8211; Nomination Form.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"La Sede \u00e8 lieta di segnalare tre opportunit\u00e0 promosse nell\u2019ambito della valorizzazione della ricerca, dell\u2019innovazione e della cooperazione scientifica internazionale, rivolte a ricercatori italiani attivi all\u2019estero, innovatori e scienziate straniere impegnate nella cooperazione scientifica bilaterale. Il termine per la presentazione delle candidature per tutti e tre i premi \u00e8 fissato al 18 settembre 2026. Le [&hellip;]","protected":false},"author":5,"featured_media":3932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-3920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=3920"}],"version-history":[{"count":1,"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3920\/revisions"}],"predecessor-version":[{"id":3928,"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/posts\/3920\/revisions\/3928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/media\/3932"}],"wp:attachment":[{"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=3920"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambcolombo.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=3920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}